{"id":5509,"date":"2013-12-02T01:05:31","date_gmt":"2013-12-02T01:05:31","guid":{"rendered":"http:\/\/algerienetwork.com\/algerie\/?p=5509"},"modified":"2013-12-02T01:05:31","modified_gmt":"2013-12-02T01:05:31","slug":"lalgerie-sapprete-a-lancer-une-fusee-dans-lespace","status":"publish","type":"post","link":"https:\/\/algerienetwork.com\/algerie\/lalgerie-sapprete-a-lancer-une-fusee-dans-lespace\/","title":{"rendered":"L\u2019Alg\u00e9rie s\u2019appr\u00eate \u00e0 lancer une fus\u00e9e dans l\u2019espace"},"content":{"rendered":"<p>Le lancement du troisi\u00e8me satellite alg\u00e9rien <strong>ALSAT 3<\/strong> pourrait intervenir au mois de janvier 2014 depuis le site de lancement de Hammaguir (d\u00e9pendant d\u2019Al-Abadla), \u00e0 120 kilom\u00e8tres au Sud-Ouest de B\u00e9char (Sud-Ouest de l\u2019<a title=\"Algeria\" href=\"http:\/\/maps.google.com\/maps?ll=36.7,3.21666666667&amp;spn=10.0,10.0&amp;q=36.7,3.21666666667%20%28Algeria%29&amp;t=h\" target=\"_blank\" rel=\"geolocation noopener noreferrer\">Alg\u00e9rie<\/a>). Un lanceur spatial alg\u00e9rien est en cours de pr\u00e9paration finale.<\/p>\n<p>Ce site avait abrit\u00e9 de 1952 \u00e0 1967, le centre interarm\u00e9es d\u2019essais d\u2019engins spatiaux (CIEES). Disposant de quatre rampes de lancement, il a permis le lancement des premiers \u00eatres vivants du programme spatial fran\u00e7ais en 1961 puis du premier satellite fran\u00e7ais <strong>Ast\u00e9rix<\/strong> avec une fus\u00e9e \u00e0 faible cout <strong>Diamant<\/strong> en 1965 avant d\u2019\u00eatre abandonn\u00e9 en 1967 conform\u00e9ment aux Accords d\u2019Evian. Le site est inhabit\u00e9 depuis jusqu\u2019\u00e0 la construction d\u2019une base a\u00e9rienne.<\/p>\n<p>Depuis 2002, l\u2019Alg\u00e9rie a d\u00e9cid\u00e9 de se doter d\u2019un programme spatial et d\u2019une agence spatiale d\u00e9nomm\u00e9e <a title=\"ASAL\" href=\"http:\/\/www.asal.dz\" target=\"_blank\" rel=\"noopener noreferrer\">ASAL<\/a> (Agence spatiale alg\u00e9rienne) avec pour objectif de lancer 10 satellites dans l\u2019espace d\u2019ici 2017.\u00a0 Le premier satellite alg\u00e9rien <strong><a title=\"AlSAT-1\" href=\"http:\/\/en.wikipedia.org\/wiki\/AlSAT-1\" target=\"_blank\" rel=\"wikipedia noopener noreferrer\">ALSAT 1<\/a><\/strong> fut lanc\u00e9 le 28 novembre 2002 par un lanceur <strong>COSMOS 3M<\/strong>\u00a0 du Cosmodrome russe de <a title=\"Plesetsk Cosmodrome\" href=\"http:\/\/maps.google.com\/maps?ll=62.916667,40.516667&amp;spn=0.01,0.01&amp;q=62.916667,40.516667%20%28Plesetsk%20Cosmodrome%29&amp;t=h\" target=\"_blank\" rel=\"geolocation noopener noreferrer\">Plesetsk<\/a>.<\/p>\n<p>Le second satellite alg\u00e9rien <strong>ALSAT 2 A<\/strong>, con\u00e7u \u00e0 <a title=\"Oran\" href=\"http:\/\/maps.google.com\/maps?ll=35.6969444444,-0.633055555556&amp;spn=0.1,0.1&amp;q=35.6969444444,-0.633055555556%20%28Oran%29&amp;t=h\" target=\"_blank\" rel=\"geolocation noopener noreferrer\">Oran<\/a>, est lanc\u00e9 le 12 juillet 2010 depuis le site de <a title=\"Sriharikota\" href=\"http:\/\/maps.google.com\/maps?ll=13.7178,80.2&amp;spn=0.1,0.1&amp;q=13.7178,80.2%20%28Sriharikota%29&amp;t=h\" target=\"_blank\" rel=\"geolocation noopener noreferrer\">Sriharikota<\/a> \u00e0 Chenna\u00ef (Sud -Est de l\u2019<a title=\"Inde\" href=\"http:\/\/maps.google.com\/maps?ll=50.8994444444,6.36277777778&amp;spn=0.01,0.01&amp;q=50.8994444444,6.36277777778%20%28Inde%29&amp;t=h\" target=\"_blank\" rel=\"geolocation noopener noreferrer\">Inde<\/a>).<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/algerienetwork.com\/algerie\/wp-content\/uploads\/2013\/12\/spatiale-alg\u00e9rie.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5510\" alt=\"spatiale alg\u00e9rie\" src=\"http:\/\/algerienetwork.com\/algerie\/wp-content\/uploads\/2013\/12\/spatiale-alg\u00e9rie.jpg\" width=\"600\" height=\"375\" \/><\/a>Photographie d\u2019une fusee Diamant (1965).<\/p>\n<p>Officiellement, l\u2019Alg\u00e9rie ne dispose d\u2019aucun programme balistique et les donn\u00e9es sur les missiles balistiques alg\u00e9riens sont parmi les rares au monde sinon totalement inconnues. Les seules donn\u00e9es disponibles semblent \u00eatre obsol\u00e8tes et remontent aux ann\u00e9es 80.<\/p>\n<p>La d\u00e9cision de l\u2019Alg\u00e9rie de se doter d\u2019un lanceur spatial n\u2019a fait l\u2019objet d\u2019aucune m\u00e9diatisation. Des informations cr\u00e9dibles font \u00e9tat d\u2019efforts intenses fournies par l\u2019arm\u00e9e alg\u00e9rienne pour se doter d\u2019informations et de techniques n\u00e9cessaires \u00e0 l\u2019\u00e9laboration d\u2019un lanceur spatial fiable et \u00e9conomique aupr\u00e8s de cinq pays.<\/p>\n<p>Plus grand pays d\u2019Afrique de par la superficie, les besoins de l\u2019Alg\u00e9rie en satellites d\u2019observation et autres se sont fait sentir de mani\u00e8re plus abrupte lors des catastrophes naturelles, puis lors de la multiplication des foyers de tension dans son environnement g\u00e9ostrat\u00e9gique imm\u00e9diat. les Alg\u00e9riens gardent \u00e9galement un mauvais souvenir du refus de certains pays de leur c\u00e9der des images satellite dans le cadre de leur lutte implacable contre le terrorisme.<\/p>\n<p>Si ces informations s\u2019av\u00e8rent exactes et que le lancement aura lieu avant avril 2014, l\u2019Alg\u00e9rie deviendra l\u2019invit\u00e9 surprise et inattendu\u00a0 du club restreint des puissances spatiales.<\/p>\n<p><a title=\"Voir tous les articles par Strategika51\" href=\"http:\/\/strategika51.wordpress.com\/author\/strategika51\/\" rel=\"author\">Strategika51<\/a><\/p>\n<p id=\"yui_3_13_0_ym1_1_1385943155879_4182\">note ; O\u00f9 se trouve Hammaguir\u00a0?\u00a0 <a id=\"yui_3_13_0_ym1_1_1385943155879_4183\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Hammaguir\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">http:\/\/fr.wikipedia.org\/wiki\/Hammaguir<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le lancement du troisi\u00e8me satellite alg\u00e9rien ALSAT 3 pourrait intervenir au mois de janvier 2014 depuis le site de lancement de Hammaguir (d\u00e9pendant d\u2019Al-Abadla), \u00e0 120 kilom\u00e8tres au Sud-Ouest de B\u00e9char (Sud-Ouest de l\u2019Alg\u00e9rie). Un lanceur spatial alg\u00e9rien est en cours de pr\u00e9paration finale. Ce site avait abrit\u00e9 de 1952 \u00e0 1967, le centre interarm\u00e9es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[816],"tags":[430],"class_list":{"0":"post-5509","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-societe","8":"tag-spatiale"},"_links":{"self":[{"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/wp\/v2\/posts\/5509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/wp\/v2\/comments?post=5509"}],"version-history":[{"count":0,"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/wp\/v2\/posts\/5509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/wp\/v2\/media?parent=5509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/wp\/v2\/categories?post=5509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/algerienetwork.com\/algerie\/wp-json\/wp\/v2\/tags?post=5509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}